{"id":12086,"date":"2023-05-02T20:46:42","date_gmt":"2023-05-02T17:46:42","guid":{"rendered":"https:\/\/antofapop.cl\/?p=12086"},"modified":"2023-05-02T20:46:42","modified_gmt":"2023-05-02T17:46:42","slug":"fentic-2023-abre-convocatoria-para-la-decimoprimera-version-del-festival-de-teatro-mas-importante-del-norte-de-chile","status":"publish","type":"post","link":"https:\/\/antofapop.cl\/index.php\/2023\/05\/02\/fentic-2023-abre-convocatoria-para-la-decimoprimera-version-del-festival-de-teatro-mas-importante-del-norte-de-chile\/","title":{"rendered":"FENTIC 2023 abre convocatoria para la d\u00e9cimoprimera versi\u00f3n del festival de teatro m\u00e1s importante del norte de Chile"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Tiempo de Lectura:<\/span>2 Minutos, 59 Segundos                <\/div>\n\n            <\/div>\n<p><strong><em>La iniciativa liderada por la Ilustre Municipalidad de Calama a trav\u00e9s de su Corporaci\u00f3n de Cultura y Turismo, recibir\u00e1 las propuestas entre el 28 de abril y el 25 de junio. Las bases pueden ser descargadas en <\/em><\/strong><a href=\"http:\/\/www.calamacultural.cl\/fentic2023\"><strong><em>www.calamacultural.cl\/fentic2023<\/em><\/strong><\/a><strong><em> .<\/em><\/strong><em>&nbsp;<\/em><\/p>\n\n\n\n<p>Las artes esc\u00e9nicas vuelven a tomarse el invierno en nuestra comuna, y es que el Festival Nacional de Teatro de Calama, FENTIC,&nbsp; regresa a su originalidad y este a\u00f1o en su duod\u00e9cima versi\u00f3n se realizar\u00e1 entre el 24 y el 30 de julio.&nbsp;<\/p>\n\n\n\n<p>En este contexto y buscando poder generar una gran convocatoria, al igual que en 2022, el \u00e1rea de cultura de la Corporaci\u00f3n de Cultura y Turismo de nuestra comuna ya comenz\u00f3 con la difusi\u00f3n para que compa\u00f1\u00edas y escuelas de teatro de diferentes lugares de Chile participen de esta connotada iniciativa.<\/p>\n\n\n\n<p>De esa forma, los artistas que quieran ser parte de este festival deben descargar las bases en la p\u00e1gina web de la entidad cultural <a href=\"http:\/\/www.calamacultural.cl\/fentic2023\">www.calamacultural.cl\/fentic2023<\/a> y enviar sus propuestas entre el 28 de abril y el 25 de junio al correo electr\u00f3nico <a href=\"mailto:fentic@calamacultural.cl\">fentic@calamacultural.cl<\/a> .<\/p>\n\n\n\n<p>Edwin Alavia Ticona, Director Ejecutivo de la Corporaci\u00f3n de Cultura y Turismo de Calama, se refiri\u00f3 a esta iniciativa e invit\u00f3 a compa\u00f1\u00edas y escuelas de teatro del pa\u00eds a que postulen a esta convocatoria.&nbsp;<\/p>\n\n\n\n<p>\u201cCon mucha alegr\u00eda comunicamos que damos el vamos al FENTIC 2023. Es maravilloso poder dar esta noticia porque una vez m\u00e1s el teatro se llenar\u00e1 de p\u00fablico, de actividad teatral, las tablas vuelven a sonar en el escenario. Esta es una convocatoria que se hace a nivel nacional para todos quienes quieran participar de esta actividad, es importante tambi\u00e9n comunicar que esta actividad va a ser en julio, en invierno, desde el 24 al 30 de julio aqu\u00ed en el Teatro Municipal\u201d.&nbsp;<\/p>\n\n\n\n<p>Por su parte, Mauricio Castro Barraza, Director del \u00c1rea de Cultura de la corporaci\u00f3n detall\u00f3: \u201cestamos muy contentos de poder convocar a todas las compa\u00f1\u00edas de Chile a participar en este festival que ya es un hito dentro de la zona norte del pa\u00eds. Estamos con una convocatoria que comienza en abril y finaliza el 25 de junio. Extraordinariamente tendremos una convocatoria de dos meses, pensando en que las compa\u00f1\u00edas puedan preparar de buena forma los montajes que se presentar\u00e1n\u201d.&nbsp;<\/p>\n\n\n\n<p>Es importante mencionar, que para este a\u00f1o la postulaci\u00f3n de las diferentes compa\u00f1\u00edas podr\u00e1n incluir videos para que as\u00ed la curator\u00eda pueda entregar una mejor propuesta teatral a toda la comunidad calame\u00f1a que participa como p\u00fablico de este festival.&nbsp;<\/p>\n\n\n\n<p><strong>Versi\u00f3n 2023<\/strong><\/p>\n\n\n\n<p>Al igual que a\u00f1os anteriores, ser\u00e1n cinco noches de competencia, adem\u00e1s de una jornada de obertura a cargo de la Escuela de Teatro Ojo del Desierto, que en esta ocasi\u00f3n presentar\u00e1 el montaje \u201cCalama Je T \u00e1ime\u201d liderado por el profesor y director de esta escuela Juan Ocho Beltr\u00e1n.&nbsp;<\/p>\n\n\n\n<p>Finalmente, este FENTIC 2023 contar\u00e1 con una noche de clausura, obra que se dar\u00e1 a conocer una vez que culmine la convocatoria y se conozca la programaci\u00f3n final de este importante certamen.&nbsp;<\/p>\n\n\n\n<p><strong>Premios&nbsp;<\/strong><\/p>\n\n\n\n<p>Como ya es tradici\u00f3n el \u201cXII Festival de Teatro de Invierno de Calama, FENTIC 2023\u201d entregar\u00e1 premios en las siguientes categor\u00edas: premio del p\u00fablico, mejor montaje y mejor actor o actriz, los \u00faltimos dos a cargo de un jurado que ser\u00e1 dado a conocer durante las pr\u00f3ximas semanas.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s de los premios en dinero que entrega este certamen, las compa\u00f1\u00edas ganadoras en las diferentes categor\u00edas se podr\u00e1n llevar una estatuilla creada en la zona y que representa el patrimonio de nuestra comuna.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La iniciativa liderada por la Ilustre Municipalidad de Calama a trav\u00e9s de su Corporaci\u00f3n de Cultura y Turismo, recibir\u00e1 las propuestas entre el 28 de abril y el 25 de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":12087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[2221,123],"tags":[662,5,7583,2942,138,2336,339,125,565],"class_list":["post-12086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calama","category-cine-tv-y-teatro","tag-chile","tag-convocatoria","tag-decimoprimera","tag-fentic","tag-festival","tag-importante","tag-norte","tag-teatro","tag-version"],"_links":{"self":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/12086"}],"collection":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/comments?post=12086"}],"version-history":[{"count":1,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/12086\/revisions"}],"predecessor-version":[{"id":12088,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/12086\/revisions\/12088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media\/12087"}],"wp:attachment":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media?parent=12086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/categories?post=12086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/tags?post=12086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}