{"id":13037,"date":"2023-07-21T22:30:12","date_gmt":"2023-07-21T19:30:12","guid":{"rendered":"https:\/\/antofapop.cl\/?p=13037"},"modified":"2023-07-21T22:30:12","modified_gmt":"2023-07-21T19:30:12","slug":"lo-que-debemos-saber-de-la-infeccion-viral-hfmd-mas-conocida-como-mano-pie-boca","status":"publish","type":"post","link":"https:\/\/antofapop.cl\/index.php\/2023\/07\/21\/lo-que-debemos-saber-de-la-infeccion-viral-hfmd-mas-conocida-como-mano-pie-boca\/","title":{"rendered":"<strong>Lo que debemos saber de la infecci\u00f3n viral HFMD m\u00e1s conocida como Mano Pie Boca<\/strong>"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Tiempo de Lectura:<\/span>6 Minutos, 30 Segundos                <\/div>\n\n            <\/div>\n<p><strong><em>Entrevista a la acad\u00e9mica de la Facultad de Ciencias del Mar y Recursos Biol\u00f3gicos de la Universidad de Antofagasta, Dra. en <\/em><\/strong><strong><em>Virolog\u00eda Molecular y Microbiolog\u00eda<\/em><\/strong><strong><em>, Margarita Lay Remolcoi, permite entender las causas y consecuencias de esta enfermedad que afecta con mayor alcance a las y los menores de edad.<\/em><\/strong><\/p>\n\n\n\n<p>La Dra. Lay es directora del Centro de Investigaci\u00f3n en Inmunolog\u00eda y Biotecnolog\u00eda Biom\u00e9dica de Antofagasta (CIIBBA), perteneciente a la Universidad de Antofagasta (UA) y junto a los estudiantes Jonatan Carvajal Contreras de la carrera de Biotecnolog\u00eda y Margott Cort\u00e9s Puga&nbsp; de Ingenier\u00eda en Biotecnolog\u00eda de la UA, se encuentran estudiando los virus que causan la enfermedad de HFMD (por sus siglas en ingl\u00e9s).<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 es la enfermedad HFMD y c\u00f3mo podemos detectarla?&nbsp;<\/strong><\/p>\n\n\n\n<p>La enfermedad mano pie boca, es una infecci\u00f3n viral causada principalmente por dos virus conocidos cient\u00edficamente como Coxsackievirus A16 (CV-A16) y Enterovirus A71 (ENV-A71). Se detecta, mediante signos cl\u00ednicos, ya que los s\u00edntomas t\u00edpicos como la fiebre, llagas en manos y boca, y decaimiento general son criterios a la hora de diagnosticar la infecci\u00f3n. Sin embargo, para confirmar o identificar el virus especifico se pueden usar t\u00e9cnicas de biolog\u00eda molecular como la PCR.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo se transmite el virus, es contagioso?&nbsp;<\/strong><\/p>\n\n\n\n<p>Si, es altamente contagiosa debido a la alta virulencia y resistencia que tienen, debido a su forma de propagaci\u00f3n, principalmente siendo de persona a persona infectada, a trav\u00e9s del contacto directo con fluidos corporales, o la respiraci\u00f3n de gotitas o superficies contaminadas por las mismas. En el caso de los ni\u00f1os peque\u00f1os tienden a explorar el mundo, a trav\u00e9s del tacto y gusto, y a menudo se llevan las manos y objetos a la boca este comportamiento facilita la infecci\u00f3n de los Enterovirus.<\/p>\n\n\n\n<p><strong>\u00bfPor qu\u00e9 la HFMD es m\u00e1s prevalente en ni\u00f1os menores de 5 a\u00f1os?<\/strong><\/p>\n\n\n\n<p>A los infantes antes de los 6 meses los protege el sistema inmune materno, a trav\u00e9s de la leche materna, posterior a este periodo se comienza a desarrollar el sistema inmune del infante el cual s\u00f3lo se ir\u00e1 fortaleciendo a medida que haya exposici\u00f3n a pat\u00f3genos y con la edad. En el caso de los adultos se da con sistema inmune debilitado.<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1les son los s\u00edntomas m\u00e1s comunes de la HFMD y cu\u00e1nto tiempo suelen durar?<\/strong><\/p>\n\n\n\n<p>El HFMD, se presenta con fiebre, dolor de garganta, erupci\u00f3n cut\u00e1nea, \u00falceras o llagas en la boca y mucosas, p\u00e9rdida de apetito, entre otros. Aunque raramente se presenta con Erupciones en Cara, Brazos, Piernas, y Genitales.<\/p>\n\n\n\n<p>Los s\u00edntomas comienzan entre 3 a 7 d\u00edas post infecci\u00f3n y su duraci\u00f3n, depender\u00e1 del sistema inmune de cada persona junto con las medidas profil\u00e1cticas empleadas, aunque generalmente los s\u00edntomas duran entre una a dos semanas (7 a 15 d\u00edas).<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 se recomienda para que ni\u00f1os o ni\u00f1as con HFMD, se sientan m\u00e1s c\u00f3modos?<\/strong><\/p>\n\n\n\n<p>Es importante proporcionar una hidrataci\u00f3n adecuada, comidas y dietas suaves o blandas que no supongan una gran exigencia el ser absorbidas por el organismo, manejo de la sintomatolog\u00eda seg\u00fan se requiera con el uso de medicamentos, descanso adecuado y tiempos de recuperaci\u00f3n prudentes.&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 complicaciones pueden surgir de la HFMD?<\/strong><\/p>\n\n\n\n<p>En general la HFMD es una infecci\u00f3n leve o autolimitada, sin embargo, en raras ocasiones pueden haber complicaciones como deshidrataci\u00f3n debida a las llagas dolorosas en la boca lo cual dificulta el consumir l\u00edquidos o complicaciones neurol\u00f3gicas como meningitis viral, encefalitis, o mielitis fl\u00e1cida.&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfExiste alg\u00fan tratamiento espec\u00edfico para la HFMD?<\/strong><\/p>\n\n\n\n<p>Actualmente no existe cura o tratamiento para la enfermedad, pero hay medidas profil\u00e1cticas que ayudan a controlar y aliviar los s\u00edntomas, por lo que se recomienda que la persona infectada lleve a cabo una buena higiene (incluyendo el lavado constante de manos), evitar tocar las zonas ulceradas, no tener contacto con personas sanas, desinfecci\u00f3n de superficies y utensilios con desinfectantes que contengan hipoclorito de sodio (cloro), ya que estos virus son resistentes al alcohol y mantener h\u00e1bitos alimenticios saludables.&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1ndo se deber\u00eda consultar al m\u00e9dico?&nbsp;<\/strong><\/p>\n\n\n\n<p>Es recomendable buscar el consejo con un profesional m\u00e9dico a la primera visualizaci\u00f3n de s\u00edntomas para obtener un diagn\u00f3stico eficiente, ya que esta suele ser confundida con la varicela.<\/p>\n\n\n\n<p><strong>\u00bfExiste alguna vacuna contra los virus que causan la HFMD?<\/strong><\/p>\n\n\n\n<p>Actualmente no existe una vacuna contra el HFMD, sin embargo hay algunas vacunas prototipo que han demostrado muy buenos resultados, estas vacunas est\u00e1n formuladas contra el Enterovirus A71. Sin embargo, \u00e9stas no han demostrado una buena eficiencia al proteger contra la HFMD producida por Coxsackievirus A16, por lo que resulta necesario seguir investigando en esta materia para formular una vacuna protectora contra ambos tipos de pat\u00f3genos.<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo se realiza la vigilancia epidemiol\u00f3gica de la HFMD?<\/strong><\/p>\n\n\n\n<p>La vigilancia epidemiol\u00f3gica de la HFMD implica una serie de medidas establecida por los organismos de salud, algunas formas en que ellos llevan a cabo esta tarea son mediante la notificaci\u00f3n de casos positivos, monitoreo de resultados cl\u00ednicos respaldado por ex\u00e1menes de laboratorio, estudio de la prevalencia de estos virus, monitoreo de salas cuna, guarder\u00edas, etc.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo han cambiado las tasas de incidencia de la HFMD en los \u00faltimos a\u00f1os?<\/strong><\/p>\n\n\n\n<p>La incidencia de HFMD cambia a\u00f1o a a\u00f1o, sin embargo, las tasas especificas de cambio depende de m\u00faltiples factores, con brotes epid\u00e9micos cada pocos a\u00f1os. A nivel global los Enterovirus que causan HFMD, est\u00e1n continuamente circulando, siendo m\u00e1s com\u00fan en regiones como Asia Oriental, y el Sureste Asi\u00e1tico. Actualmente, no se posee un registro actualizado de cifras sobre la incidencia de muertes a causa de HFMD, sin embargo, hay cifras sobre la incidencia de esta enfermedad alrededor del mundo, en donde la tasa de mortalidad de HFMD varia entre el 0.02 al 6%.<\/p>\n\n\n\n<p><strong>\u00bfExiste alguna estacionalidad en los brotes de HFMD?<\/strong><\/p>\n\n\n\n<p>En regiones de clima templado los casos tienden a presentarse mayormente en verano y principios de oto\u00f1o, mientras que en las regiones tropicales pueden ocurrir brotes espor\u00e1dicos todo el a\u00f1o a excepci\u00f3n de las \u00e9pocas con lluvia.&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo afecta la HFMD a las comunidades con recursos limitados en t\u00e9rminos de atenci\u00f3n m\u00e9dica?<\/strong><\/p>\n\n\n\n<p>Las comunidades con recursos limitados pueden verse afectadas debido al acceso a la atenci\u00f3n m\u00e9dica oportuna y de calidad, esto puede suponer un retraso en el diagn\u00f3stico y tratamiento. La higiene y saneamiento puede suponer una dificultad muy grande debido a que el virus se propaga mediante el contacto f\u00edsico, y las instalaciones de cuidado infantil pueden no estar preparadas para brindar las medidas de seguridad y aislamiento en casos positivos.&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1les son los desaf\u00edos m\u00e1s grandes que enfrentan los profesionales de la salud p\u00fablica en el control de la HFMD?<\/strong><\/p>\n\n\n\n<p>Los desaf\u00edos son la prevenci\u00f3n de la propagaci\u00f3n del virus, el control y saneamiento en materias infantiles, la vacunaci\u00f3n, las herramientas de detecci\u00f3n temprana y accesible y la educaci\u00f3n de la comunidad para la prevenci\u00f3n y el cuidado contra el HFMD.&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1les son los pasos que se pueden tomar desde la salud p\u00fablica para mitigar los brotes de HFMD?<\/strong><\/p>\n\n\n\n<p>Algunas medidas que pueden ser abordadas desde el \u00e1mbito pol\u00edtico son mejorar las medidas de higiene de los establecimientos de cuidado como jardines y guarder\u00edas, implementar pol\u00edticas de salud p\u00fablica como programas de vacunaci\u00f3n, fortalecer la vigilancia de la infecci\u00f3n, promoviendo planes de vigilancia y estrategias de monitoreo, o incrementando el apoyo y los recursos para mejorar e impulsar la investigaci\u00f3n de vacunas y medidas profil\u00e1cticos.&nbsp;<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1l es el papel de la investigaci\u00f3n en la mejora de la prevenci\u00f3n y el tratamiento de la HFMD?<\/strong><\/p>\n\n\n\n<p>La investigaci\u00f3n juega un papel clave en la mejora y prevenci\u00f3n de HFMD, ya que contribuye al entendimiento de la enfermedad, el desarrollo de vacunas aptas y mejores para combatir y prevenir la infecci\u00f3n, el mejoramiento de los tratamientos para ayudar con las medidas profil\u00e1cticas, adem\u00e1s de proporcionar una educaci\u00f3n y comunicaci\u00f3n en materias de salud p\u00fablica.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevista a la acad\u00e9mica de la Facultad de Ciencias del Mar y Recursos Biol\u00f3gicos de la Universidad de Antofagasta, Dra. en Virolog\u00eda Molecular y Microbiolog\u00eda, Margarita Lay Remolcoi, permite entender&hellip;<\/p>\n","protected":false},"author":1,"featured_media":13038,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2405,6698],"tags":[7826,8009,8008,3500,8010,3299],"class_list":["post-13037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-region","category-salud","tag-boca","tag-hfmd","tag-infeccion","tag-mano","tag-pie","tag-viral"],"_links":{"self":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/13037"}],"collection":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/comments?post=13037"}],"version-history":[{"count":1,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/13037\/revisions"}],"predecessor-version":[{"id":13039,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/13037\/revisions\/13039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media\/13038"}],"wp:attachment":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media?parent=13037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/categories?post=13037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/tags?post=13037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}