{"id":16251,"date":"2024-07-26T19:06:51","date_gmt":"2024-07-26T16:06:51","guid":{"rendered":"https:\/\/antofapop.cl\/?p=16251"},"modified":"2024-07-26T19:06:53","modified_gmt":"2024-07-26T16:06:53","slug":"proyectos-de-nomada-de-usqai-se-adjudican-fondo-publico-para-desarrollar-sus-emprendimientos","status":"publish","type":"post","link":"https:\/\/antofapop.cl\/index.php\/2024\/07\/26\/proyectos-de-nomada-de-usqai-se-adjudican-fondo-publico-para-desarrollar-sus-emprendimientos\/","title":{"rendered":"<strong>Proyectos de N\u00f3mada de USQAI se adjudican fondo p\u00fablico para desarrollar sus emprendimientos<\/strong>"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Tiempo de Lectura:<\/span>3 Minutos, 48 Segundos                <\/div>\n\n            <\/div>\n<p><em><strong>Estudiantes de UCN Coquimbo y CEDUC Antofagasta que participaron en N\u00f3mada 2023 se adjudicaron el fondo semilla inicia de Corfo, que les permitir\u00e1 escalar sus proyectos.<\/strong><\/em><\/p>\n\n\n\n<p>Fue en el programa N\u00f3mada del <a href=\"https:\/\/usqai.ucn.cl\/\">Laboratorio de Emprendimiento USQAI<\/a> de la <a href=\"https:\/\/www.ucn.cl\/\">Universidad Cat\u00f3lica del Norte (UCN)<\/a> donde nace Aqcuanalytic (actualmente ECUAI), conformado por estudiantes de la UCN Coquimbo, quienes este mes se adjudicaron el Fondo Semilla Inicia de Corfo de $17 millones.<\/p>\n\n\n\n<p>El equipo se conform\u00f3 durante el desarrollo del programa, donde estudiantes de cuarto y quinto a\u00f1o de Ingenier\u00eda Civil Industrial dieron vida al proyecto, basado en la detecci\u00f3n y predicci\u00f3n de fugas con Machine Learning y modelos de serie de tiempo a partir de informaci\u00f3n recopilada mediante sensores, datos que el usuario podr\u00e1 visualizar a trav\u00e9s de una plataforma web.<\/p>\n\n\n\n<p>El equipo obtuvo el 3\u00b0 lugar en N\u00f3mada 2023, encontrando potencial en su proyecto. Ante esto, decidieron postular al Semilla Inicia de Corfo, adjudicando este fondo en julio de 2024. <em>\u201cPostulamos con la fe de ganar, cuando recib\u00ed el mensaje no lo pod\u00eda creer.&nbsp; Sabemos que nos queda mucho camino por delante, pero estamos seguros de que con el apoyo de USQAI vamos a poder llegar a nuestra meta que es generar un producto tangible con el que podamos ayudar a la&nbsp; cuarta regi\u00f3n con el tema del agua\u201d<\/em>, se\u00f1al\u00f3 Fernanda Adones, del equipo ECUAI y estudiante de la UCN Coquimbo.<\/p>\n\n\n\n<p>Por otro lado, Neurodiversi\u00f3n es una apuesta que busca mejorar la calidad de vida por medio de un kit preventivo de desarrollo, ofreciendo capacitaci\u00f3n al cliente junto a un seguimiento al usuario a trav\u00e9s de una app personalizada. Este equipo compuesto madre e hija, quisieron fortalecer su idea en N\u00f3mada 2023, donde pudieron trabajar un modelo de negocio, presentar el pitch y trabajar otras competencias para no s\u00f3lo fortalecer su emprendimiento sino que su esp\u00edritu emprendedor.<\/p>\n\n\n\n<p>Pola Ram\u00edrez, estudiante de CEDUC Antofagasta y parte del equipo de Neurodiversi\u00f3n, destaca el apoyo de USQAI en el proceso de postulaci\u00f3n al Semilla Inicia de Corfo, apuntando que el acompa\u00f1amiento de los monitores (estudiantes UCN) y equipo USQAI fue clave para poder hacer una buena postulaci\u00f3n. Ella fue la primera en recibir la noticia de la adjudicaci\u00f3n del fondo. <em>\u201cCuando me enter\u00e9 de la adjudicaci\u00f3n, llam\u00e9 a mi mam\u00e1 y luego avis\u00e9 a USQAI. Est\u00e1bamos felices. Estamos con muchas ganas de crecer\u201d<\/em>, afirm\u00f3.&nbsp;<\/p>\n\n\n\n<p>N\u00f3mada ha alcanzado progresivamente varios de sus objetivos fundamentales. Los participantes han logrado obtener fondos, como el Semilla Inicia, permiti\u00e9ndoles desarrollar y materializar sus proyectos innovadores. Este \u00e9xito refleja no s\u00f3lo el esfuerzo y la dedicaci\u00f3n de los miembros, sino tambi\u00e9n la eficacia del programa en brindar las herramientas y el apoyo necesarios para el crecimiento y la realizaci\u00f3n de ideas creativas y emprendedoras.<\/p>\n\n\n\n<p><strong>OTROS PROYECTOS<\/strong><\/p>\n\n\n\n<p>El impacto del programa N\u00f3mada no es un fen\u00f3meno reciente. En la&nbsp; primera versi\u00f3n de N\u00f3mada realizada durante el 2022 naci\u00f3 \u201cFlui\u201d, una apuesta que busca recolectar servicios la plataforma para apoyar la organizaci\u00f3n de eventos y celebraciones, reuniendo a diversos proveedores del rubro, liderada por Gemita Huircap\u00e1n, estudiante de Geolog\u00eda de la UCN Antofagasta. <em>\u201cN\u00f3mada me entreg\u00f3 las herramientas, redes y apoyo para que mi idea se hiciera realidad. Adem\u00e1s, me permiti\u00f3 crecer en cuanto al perfil emprendedor y as\u00ed dirigir mejor mi emprendimiento actual y lograr adjudicarnos el fondo Semilla Inicia de Corfo durante 2023\u201d<\/em>, sostuvo la estudiante.<\/p>\n\n\n\n<p>Durante 2022, Juguetes Allikum, emprendimiento de Iquique liderado por Paulo Araya, que son juguetes con realidad aumentada hechos con madera de pallets, tambi\u00e9n form\u00f3 parte de la primera versi\u00f3n de N\u00f3mada, adjudic\u00e1ndose durante 2023 el Semilla Inicia de Corfo, para continuar potenciando su proyecto. <em>\u201cConoc\u00ed a USQAI durante 2021 en ETM Day. Cuando vi que estaba el programa N\u00f3mada, quise participar de inmediato. Viajaba todas las semanas desde Iquique a Antofagasta para poder vivir el programa y madurar mi proyecto. Me ayudaron a postular al Semilla Inicia y me lo adjudiqu\u00e9 durante 2023\u201d<\/em>, puntualiz\u00f3 Paulo Araya, CEO de Allikum.<\/p>\n\n\n\n<p>Estos ejemplos reflejan c\u00f3mo el programa N\u00f3mada ha sido un programa para el desarrollo de emprendedores, proporcionando no s\u00f3lo las herramientas y el apoyo necesarios, sino tambi\u00e9n el impulso para acceder a financiamiento significativo.<\/p>\n\n\n\n<p>A trav\u00e9s de la combinaci\u00f3n de creatividad, redes de apoyo y desarrollo de competencias, el programa ha demostrado ser un verdadero motor para el emprendimiento en las regiones de Antofagasta y de Coquimbo.<\/p>\n\n\n\n<p>Con historias de \u00e9xito que validan su impacto, N\u00f3mada contin\u00faa consolid\u00e1ndose con una nueva versi\u00f3n para trabajar las ideas de emprendimiento. Las inscripciones est\u00e1n abiertas hasta el 16 de agosto en <a href=\"http:\/\/usqai.ucn.cl\/nomada\">usqai.ucn.cl\/nomada<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudiantes de UCN Coquimbo y CEDUC Antofagasta que participaron en N\u00f3mada 2023 se adjudicaron el fondo semilla inicia de Corfo, que les permitir\u00e1 escalar sus proyectos. Fue en el programa&hellip;<\/p>\n","protected":false},"author":1,"featured_media":16252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[659,2405],"tags":[3791,416,2315,500,758,3790],"class_list":["post-16251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emprendimiento","category-region","tag-emprendimientos","tag-fondo","tag-nomada","tag-proyectos","tag-publico","tag-usqai"],"_links":{"self":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/16251"}],"collection":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/comments?post=16251"}],"version-history":[{"count":1,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/16251\/revisions"}],"predecessor-version":[{"id":16253,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/16251\/revisions\/16253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media\/16252"}],"wp:attachment":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media?parent=16251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/categories?post=16251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/tags?post=16251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}