{"id":17023,"date":"2024-08-30T17:31:20","date_gmt":"2024-08-30T14:31:20","guid":{"rendered":"https:\/\/antofapop.cl\/?p=17023"},"modified":"2024-08-30T17:31:20","modified_gmt":"2024-08-30T14:31:20","slug":"fondo-efecto-colectivo-premia-a-fundacion-teatro-a-mil-y-la-balanza-con-proyecto-que-busca-fomentar-las-artes-escenicas-desde-la-infancia","status":"publish","type":"post","link":"https:\/\/antofapop.cl\/index.php\/2024\/08\/30\/fondo-efecto-colectivo-premia-a-fundacion-teatro-a-mil-y-la-balanza-con-proyecto-que-busca-fomentar-las-artes-escenicas-desde-la-infancia\/","title":{"rendered":"Fondo Efecto Colectivo premia a Fundaci\u00f3n\u00a0Teatro\u00a0a\u00a0Mil\u00a0y La Balanza con proyecto que busca fomentar las artes esc\u00e9nicas desde la infancia"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Tiempo de Lectura:<\/span>3 Minutos, 9 Segundos                <\/div>\n\n            <\/div>\n<p><em><strong>En una instancia de di\u00e1logo y colaboraci\u00f3n, se realiz\u00f3 el lanzamiento de la aceleradora de impacto educativo de Efecto Colectivo a trav\u00e9s de las ocho iniciativas galardonadas y se reunieron para definir una agenda com\u00fan de trabajo con mirada a futuro.<\/strong><\/em><\/p>\n\n\n\n<p>Con talleres de co-dise\u00f1o de innovaci\u00f3n colaborativa, se dio inicio al trabajo de implementaci\u00f3n de los&nbsp;<strong>proyectos ganadores de Efecto Colectivo<\/strong>, alianza colaborativa impulsada por Fundaci\u00f3n Reimagina con el apoyo de BHP Foundation, que busca&nbsp;<strong>transformar la educaci\u00f3n del pa\u00eds para responder con \u00e9xito a los desaf\u00edos de hoy y ma\u00f1ana<\/strong>. Una de las iniciativas ganadoras fue el&nbsp;<strong>proyecto &#8220;Teatro&nbsp;en la Educaci\u00f3n &#8211; TELE&#8221; promovido por la Fundaci\u00f3n&nbsp;Teatro&nbsp;a&nbsp;Mil&nbsp;y La Balanza<\/strong>.<\/p>\n\n\n\n<p>La&nbsp;<strong>directora de Fundaci\u00f3n Reimagina, Ana Mar\u00eda Raad<\/strong>, destac\u00f3 la importancia de este hito inicial y su relevancia como un espacio para construir una visi\u00f3n en com\u00fan de los proyectos que se desarrollar\u00e1n en distintas regiones de Chile. &#8220;Cada uno de ellos tiene el potencial de transformar la experiencia educativa, enfoc\u00e1ndose en distintas \u00e1reas y estamentos de la comunidad escolar. Nuestra visi\u00f3n es que&nbsp;<strong>si a ese potencial le entregamos acompa\u00f1amiento y las herramientas necesarias para que puedan cumplir sus objetivos y escalar, lograremos el efecto colectivo al que aspiramos<\/strong>, para que los estudiantes puedan lograr los aprendizajes que necesitan para un mejor futuro&#8221;, dijo.<\/p>\n\n\n\n<p>Del mismo modo,&nbsp;<strong>Alejandra Garc\u00e9s, directora del Programa Chile BHP Foundation,<\/strong>&nbsp;plante\u00f3 que &#8220;a trav\u00e9s de Efecto Colectivo buscamos impactar positivamente en el sistema educativo articulando colaboraciones valiosas con diferentes organizaciones y poniendo en valor las variables que inciden en el desarrollo escolar. Es por ello que&nbsp;<strong>trabajamos para reducir las brechas de aprendizaje, centr\u00e1ndonos en impulsar habilidades del siglo XXI, cognitivas y socioemocionales e incorporando el buen uso de tecnolog\u00edas<\/strong>. Es mucho m\u00e1s que la suma de las partes, es la convicci\u00f3n de que unidos podemos mejorar las oportunidades de estudiantes y generar un cambio&#8221;.<\/p>\n\n\n\n<p>La innovadora propuesta de&nbsp;<strong>Fundaci\u00f3n&nbsp;Teatro&nbsp;a&nbsp;Mil&nbsp;y La Balanza busca que se incorpore al curr\u00edculo escolar la asignatura de artes esc\u00e9nicas, contribuyendo al desarrollo de&nbsp; habilidades que resultan claves para los ni\u00f1os, ni\u00f1as y j\u00f3venes de&nbsp; educaci\u00f3n b\u00e1sica en el siglo XXI.<\/strong>&nbsp;Para ello, se busca capacitar en metodolog\u00edas innovadoras a sus profesores, promoviendo el aprendizaje l\u00fadico, activo y participativo; compartiendo estrategias del mundo del&nbsp;teatro&nbsp;a la sala de clases. Esto, enfocado en las regiones Metropolitana, Antofagasta y Biob\u00edo.<\/p>\n\n\n\n<p>En ese sentido,\u00a0<strong>Paula Eche\u00f1ique, Directora de Planificaci\u00f3n y Proyectos de Fundaci\u00f3n\u00a0Teatro\u00a0a\u00a0Mil,<\/strong> plantea que &#8220;desde 2016 estamos impulsando este programa en la Regi\u00f3n Metropolitana y ahora lo podremos escalar a las regiones de Antofagasta y Biob\u00edo. Estamos en un momento propicio para reflexionar sobre qu\u00e9 queremos para las generaciones del futuro. De hecho, la propuesta de actualizaci\u00f3n de bases curriculares que est\u00e1 impulsando el Ministerio de Educaci\u00f3n propone<strong>\u00a0integrar las artes esc\u00e9nicas desde la primera infancia<\/strong>. Nos gustar\u00eda poner en di\u00e1logo esa actualizaci\u00f3n con\u00a0<strong>metodolog\u00edas como la pedagog\u00eda teatral\u00a0<\/strong>desarrollada por La Balanza, que ha demostrado impactar positiva y profundamente el aprendizaje y la formaci\u00f3n de ni\u00f1os, ni\u00f1as y j\u00f3venes, a trav\u00e9s de la implementaci\u00f3n del programa\u00a0Teatro\u00a0en la Educaci\u00f3n&#8221;.\u00a0<br><br>Desde Fundaci\u00f3n\u00a0Teatro\u00a0a\u00a0Mil\u00a0recalcan que, seg\u00fan su experiencia en proyectos similares en Santiago, menos del 50% de los estudiantes ha ido al\u00a0teatro\u00a0alguna vez, por lo que con este tipo de programas se busca poner al servicio de los ni\u00f1os, ni\u00f1as y j\u00f3venes de dichas regiones todos los recursos que ofrece el\u00a0teatro\u00a0en la educaci\u00f3n para abrir una puerta de acceso a las artes y la cultura y para promover el desarrollo de las habilidades del siglo XXI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una instancia de di\u00e1logo y colaboraci\u00f3n, se realiz\u00f3 el lanzamiento de la aceleradora de impacto educativo de Efecto Colectivo a trav\u00e9s de las ocho iniciativas galardonadas y se reunieron&hellip;<\/p>\n","protected":false},"author":1,"featured_media":17024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[123,2405],"tags":[9292,235,9293,1465,1020,526,416,10,2673,1032,373,6164,125],"class_list":["post-17023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine-tv-y-teatro","category-region","tag-a-mil","tag-artes","tag-balanza","tag-colectivo","tag-efecto","tag-escenicas","tag-fondo","tag-fundacion","tag-infancia","tag-mil","tag-proyecto","tag-regiones","tag-teatro"],"_links":{"self":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/17023"}],"collection":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/comments?post=17023"}],"version-history":[{"count":1,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/17023\/revisions"}],"predecessor-version":[{"id":17025,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/17023\/revisions\/17025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media\/17024"}],"wp:attachment":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media?parent=17023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/categories?post=17023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/tags?post=17023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}