{"id":20432,"date":"2025-09-16T16:08:14","date_gmt":"2025-09-16T13:08:14","guid":{"rendered":"https:\/\/antofapop.cl\/?p=20432"},"modified":"2025-09-16T16:08:15","modified_gmt":"2025-09-16T13:08:15","slug":"con-ceremonia-ancestral-drt-renueva-su-compromiso-con-la-madre-tierra","status":"publish","type":"post","link":"https:\/\/antofapop.cl\/index.php\/2025\/09\/16\/con-ceremonia-ancestral-drt-renueva-su-compromiso-con-la-madre-tierra\/","title":{"rendered":"Con ceremonia ancestral DRT renueva su compromiso con la Madre Tierra"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Tiempo de Lectura:<\/span>2 Minutos, 48 Segundos                <\/div>\n\n            <\/div>\n<p><em><strong>A la espera del amanecer, desde la Fase 38 de la mina, trabajadores(as), supervisores(as), ejecutivos(as) y contratistas se unieron para agradecer y pedir protecci\u00f3n para un nuevo ciclo, as\u00ed como recordar a las v\u00edctimas fatales del reciente accidente en Divisi\u00f3n El Teniente y reforzar la cultura preventiva en DRT.<\/strong><\/em><\/p>\n\n\n\n<p>En un ambiente cargado de simbolismo y respeto por las tradiciones ancestrales, en Divisi\u00f3n Radomiro Tomic (DRT) se realiz\u00f3 el \u201cPago a la Tierra 2025\u201d. La actividad, fue dirigida por el Yatiri (\u201cHombre sabio\u201d en lengua ancestral) Germ\u00e1n Gonz\u00e1lez, de la comunidad lickanantay de Caspana, y cont\u00f3 con la participaron de alrededor de 40 personas entre trabajadores(as), supervisores(as), ejecutivos(as) y contratistas.<\/p>\n\n\n\n<p>Siguiendo la costumbre, se ofrendaron a la Madre Tierra (Pat\u2019ta Hoiri en lengua Kunza) hojas de coca, licores e inciensos, con el fin de agradecer por las riquezas entregadas junto con pedir por un ciclo de abundancia, protecci\u00f3n y seguridad para toda la familia de RT, as\u00ed como recordar a las v\u00edctimas fatales del reciente accidente en Divisi\u00f3n El Teniente y reforzar la cultura preventiva en la Divisi\u00f3n.<\/p>\n\n\n\n<p>Para Claudia Dom\u00ednguez, el Pago a la Tierra tuvo un significado especial ya que es el primero que lidera en su retorno como gerenta general de Radomiro Tomic. \u201cEstamos con parte del equipo celebrando esta ceremonia con mucha conexi\u00f3n y agradeciendo lo que nos ha dado la tierra y pidi\u00e9ndole tambi\u00e9n que nos acompa\u00f1e en el futuro que tenemos. Con esta ceremonia tan importante, queremos seguir insistiendo cu\u00e1l es el eje central de cada d\u00eda de los que trabajamos en esta Divisi\u00f3n, el cuidado, la seguridad, eso va a ser el centro de todo lo que hagamos\u201d, destac\u00f3.<\/p>\n\n\n\n<p>Desde la Gerencia de Sustentabilidad de las Operaciones Norte de Codelco, H\u00e9ctor Cort\u00e9s, asesor senior, resalt\u00f3 la importancia de mantener viva esta tradici\u00f3n porque \u201cesta ceremonia es un evento fundamental para conectar y, sobre todo, agradecer a la Madre Tierra por la riqueza que nos entrega. Y qu\u00e9 mejor que el contacto directo con la misma comunidad y, sobre todo, con su hombre sabio, que es el Yatiri\u201d.<\/p>\n\n\n\n<p>\u201cHay que agradecer a la Madre Tierra porque es un ser vivo que nos da de todo. Por lo tanto, nuestros antepasados siempre hac\u00edan estas ceremonias para evitar accidentes, para que aparezca m\u00e1s cobre y por todo lo que es la producci\u00f3n. Desearles el mejor de los \u00e9xitos y que sea en buena hora\u201d, manifest\u00f3 el Yatiri Germ\u00e1n Gonz\u00e1lez.<\/p>\n\n\n\n<p>La ceremonia tambi\u00e9n fue valorada por las dirigencias sindicales y trabajadores de la Divisi\u00f3n, quienes destacaron la importancia de entregar ofrendas a la Pachamama y pedir por el bienestar de los y las trabajadoras de Radomiro Tomic.<\/p>\n\n\n\n<p>\u201cComo trabajadores de la Divisi\u00f3n, es relevante esta ceremonia, para tener el permiso de la tierra para poder trabajar y extraer cobre y as\u00ed aportar al pa\u00eds\u201d, coment\u00f3 Luis Z\u00fa\u00f1iga, Secretario del Sindicato de Establecimiento Planta Administraci\u00f3n.<\/p>\n\n\n\n<p>Cristian Espinoza, Operador Mina del turno E1, agreg\u00f3 que \u201cgracias a la Madre Tierra tenemos los recursos y tenemos trabajo. Debemos darle gracias tambi\u00e9n para que sea generosa con nuestro mineral para el presente y para el futuro\u201d.<\/p>\n\n\n\n<p>Este acto de agradecimiento y petici\u00f3n marc\u00f3 el inicio de un nuevo ciclo en la Divisi\u00f3n Radomiro Tomic, con el compromiso de seguir construyendo un futuro seguro, sustentable y en armon\u00eda con las ra\u00edces culturales del territorio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la espera del amanecer, desde la Fase 38 de la mina, trabajadores(as), supervisores(as), ejecutivos(as) y contratistas se unieron para agradecer y pedir protecci\u00f3n para un nuevo ciclo, as\u00ed como&hellip;<\/p>\n","protected":false},"author":1,"featured_media":20433,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2221,9185],"tags":[4102,3015,3687,10301,690,1124,8883],"class_list":["post-20432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calama","category-mineria","tag-ancestral","tag-ceremonia","tag-compromiso","tag-drt","tag-madre","tag-tierra","tag-tomic"],"_links":{"self":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/20432"}],"collection":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/comments?post=20432"}],"version-history":[{"count":1,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/20432\/revisions"}],"predecessor-version":[{"id":20434,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/20432\/revisions\/20434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media\/20433"}],"wp:attachment":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media?parent=20432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/categories?post=20432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/tags?post=20432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}