{"id":20938,"date":"2025-10-26T23:51:37","date_gmt":"2025-10-26T20:51:37","guid":{"rendered":"https:\/\/antofapop.cl\/?p=20938"},"modified":"2025-11-28T15:30:35","modified_gmt":"2025-11-28T12:30:35","slug":"nueva-fecha-antofagasta-en-100-palabras-premiara-a-sus-ganadores-el-28-de-octubre","status":"publish","type":"post","link":"https:\/\/antofapop.cl\/index.php\/2025\/10\/26\/nueva-fecha-antofagasta-en-100-palabras-premiara-a-sus-ganadores-el-28-de-octubre\/","title":{"rendered":"Nueva fecha: Antofagasta en 100 Palabras premiar\u00e1 a sus ganadores el 28 de octubre"},"content":{"rendered":"<div class='booster-block booster-read-block'>\n                <div class=\"twp-read-time\">\n                \t<i class=\"booster-icon twp-clock\"><\/i> <span>Tiempo de Lectura:<\/span>1 Minutos, 58 Segundos                <\/div>\n\n            <\/div>\n<p><strong><em>El concurso de cuentos breves m\u00e1s importante del norte de Chile, presentado por Escondida | BHP y Fundaci\u00f3n Plagio, distinguir\u00e1 a los mejores relatos de su edici\u00f3n \u2013r\u00e9cord hist\u00f3rico en partici\u00f3n\u2013 en 8 categor\u00edas, en una ceremonia gratuita y abierta a todo p\u00fablico el pr\u00f3ximo martes 28 de octubre, a las 19:30 horas, en la Fundaci\u00f3n Minera Escondida, previa inscripci\u00f3n en la web del concurso.<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>La ceremonia contar\u00e1 con la participaci\u00f3n de la destacada actriz antofagastina Pamela Meneses, quien realizar\u00e1 una lectura dramatizada de los cuentos ganadores, mientras que la Orquesta de la Universidad de Antofagasta\u00a0junto a su director Miguel Toro,\u00a0se encargar\u00e1n de la musicalizaci\u00f3n en vivo de los relatos. La animaci\u00f3n del evento estar\u00e1 a cargo de la tambi\u00e9n actriz chilena, Elvira Cristi, quien guiar\u00e1 al p\u00fablico en la revelaci\u00f3n de los ganadores.<\/em><\/strong><\/p>\n\n\n\n<p>\u201c\u00bfTe lo imaginas?\u201d fue la pregunta que acompa\u00f1\u00f3 la XVI edici\u00f3n de Antofagasta en 100 Palabras, que invit\u00f3 a so\u00f1ar en torno a la regi\u00f3n y a explorar la creatividad a trav\u00e9s de las letras. La convocatoria, abierta entre abril y julio de 2025, recibi\u00f3 un r\u00e9cord hist\u00f3rico de m\u00e1s de 13.450 relatos breves, superando todas las marcas anteriores y reflejando el masivo entusiasmo de la comunidad por contar sus historias.<\/p>\n\n\n\n<p>La selecci\u00f3n de los relatos ganadores estuvo a cargo de un jurado de lujo compuesto por la reconocida autora Alejandra Costamagna, el escritor antofagastino Rodrigo Ramos Ba\u00f1ados y la autora Mar\u00eda Paz Rodr\u00edguez. De las 8 categor\u00edas premiadas, el Primer Lugar recibir\u00e1 $2.000.000; las categor\u00edas Talento Joven, Talento Mayor, Talento Infantil, Mejor Relato de la Memoria, Talento Breve y dos menciones honrosas recibir\u00e1n $250.000 cada una. Los establecimientos educacionales m\u00e1s participativos tambi\u00e9n ser\u00e1n reconocidos.<\/p>\n\n\n\n<p><strong>16 A\u00d1OS CAPTURANDO LA ESENCIA DE LA REGI\u00d3N<\/strong><\/p>\n\n\n\n<p><br>Desde su creaci\u00f3n en 2009, Antofagasta en 100 Palabras se ha consolidado como una plataforma fundamental para la literatura y la identidad local. Ha recibido decenas de miles de relatos, publicado a cientos de autores y distribuido gratuitamente miles de libros de bolsillo con los mejores cuentos, acercando la lectura y la escritura a todos los rincones de la regi\u00f3n.<\/p>\n\n\n\n<p>Antofagasta en 100 Palabras es presentado por Escondida | BHP y Fundaci\u00f3n Plagio. Conoce m\u00e1s detalles de Antofagasta en 100 Palabras en el<a href=\"https:\/\/trackercl1.fidelizador.com\/L10E9CD10G780811BDHA9DAAA09F1JF46D193671K10E9CD1099968ED34AF33788915B6B\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;sitio web<\/a>&nbsp;del certamen y en sus cuentas de&nbsp;<a href=\"https:\/\/trackercl1.fidelizador.com\/L10E9CD10G780811BDHA9DAAA09F1JF46D1936E2K10E9CD1099968ED34AF33788915B6B\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>,&nbsp;<a href=\"https:\/\/trackercl1.fidelizador.com\/L10E9CD10G780811BDHA9DAAA09F1JF46D1936E7K10E9CD1099968ED34AF33788915B6B\" target=\"_blank\" rel=\"noreferrer noopener\">TikTok<\/a>&nbsp;y&nbsp;<a href=\"https:\/\/trackercl1.fidelizador.com\/L10E9CD10G780811BDHA9DAAA09F1JF46D19AFFAK10E9CD1099968ED34AF33788915B6B\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concurso de cuentos breves m\u00e1s importante del norte de Chile, presentado por Escondida | BHP y Fundaci\u00f3n Plagio, distinguir\u00e1 a los mejores relatos de su edici\u00f3n \u2013r\u00e9cord hist\u00f3rico en&hellip;<\/p>\n","protected":false},"author":1,"featured_media":20694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2,197],"tags":[199,36,2631,1537,196,200],"class_list":["post-20938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antofagasta","category-libros","tag-199","tag-antofagasta","tag-fecha","tag-ganadores","tag-nueva","tag-palabras"],"_links":{"self":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/20938"}],"collection":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/comments?post=20938"}],"version-history":[{"count":1,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/20938\/revisions"}],"predecessor-version":[{"id":20939,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/posts\/20938\/revisions\/20939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media\/20694"}],"wp:attachment":[{"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/media?parent=20938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/categories?post=20938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antofapop.cl\/index.php\/wp-json\/wp\/v2\/tags?post=20938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}